{"id":11426,"date":"2019-07-31T15:55:00","date_gmt":"2019-07-31T13:55:00","guid":{"rendered":"https:\/\/www.mago-erp.com\/?page_id=11426"},"modified":"2021-02-04T15:34:37","modified_gmt":"2021-02-04T14:34:37","slug":"framework","status":"publish","type":"page","link":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework","title":{"rendered":"TaskBuilder Framework"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; parallax=&#8221;content-moving&#8221; wrap_container=&#8221;yes&#8221; css=&#8221;.vc_custom_1526891136881{margin-bottom: 40px !important;padding-top: -100px !important;background-color: #ffffff !important;background-position: 0 0;background-repeat:-repeat;}&#8221; el_class=&#8221;bg-img-cover&#8221;][vc_column animation_type=&#8221;fadeIn&#8221;][rev_slider_vc alias=&#8221;it-_taskbuilderframework&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; wrap_container=&#8221;yes&#8221; text_align=&#8221;left&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; css=&#8221;.vc_custom_1525957325142{margin-top: 20px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 0px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 40px !important;padding-left: 0px !important;}&#8221; el_class=&#8221;bg-custom-color-1&#8243;][vc_column][vc_custom_heading text=&#8221;TaskBuilder Framework \u00e8 la base applicativa su cui puoi sviluppare nuovi progetti, l&#8217;infrastruttura di supporto su cui \u00e8 basato il sistema gestionale. Il Framework definisce infatti l&#8217;architettura globale di Mago4 e ti supporta nella creazione di progetti, estendendo le funzionalit\u00e0 dell&#8217;ERP.&#8221; font_container=&#8221;tag:h2|font_size:22|text_align:left|color:%230a0a0a|line_height:1.5&#8243; google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:300%20light%20regular%3A300%3Anormal&#8221;][vc_custom_heading text=&#8221;TaskBuilder Framework ti offre molteplici strumenti per gestire le risorse gestionali secondo procedure affermate, solide e profondamente sicure, ottimizzando e razionalizzando i processi e le applicazioni ERP.&#8221; font_container=&#8221;tag:h2|font_size:22|text_align:left|color:%230a0a0a|line_height:1.5&#8243; google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:300%20light%20regular%3A300%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; wrap_container=&#8221;yes&#8221; text_align=&#8221;left&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; css=&#8221;.vc_custom_1525416056455{margin-top: 40px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 0px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 40px !important;padding-left: 0px !important;}&#8221; el_class=&#8221;bg-custom-color-1&#8243;][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1527080165107{margin-bottom: 60px !important;}&#8221;][vc_empty_space][vc_column_text]\n<h1>Cosa ti offre TaskBuilder Framework?<\/h1>\n[\/vc_column_text][vc_empty_space][vc_column_text]Con il componente TaskBuilder Framework della famiglia Mago4 hai a disposizione una struttura capace di dare forza alle tue soluzioni e di supportarti nel quotidiano, grazie strumenti pensati apposta per aumentare la produttivit\u00e0 aziendale. La modularit\u00e0 di Mago4, per esempio, \u00e8 una diretta conseguenza del modello dell&#8217;architettura, in cui la struttura logica rimane separata dall&#8217;interfaccia utente.<\/p>\n<p>Scopri tutte le funzionalit\u00e0 a tua disposizione per migliorare il flusso delle informazioni, creare e gestire la reportistica, condividere facilmente le informazioni con gli altri ed automatizzare i processi ripetitivi.[\/vc_column_text][vc_empty_space]<style>.porto-info-list81de0d7b252625259d0c0244a8c0a5bf i { font-size: 16px; }<\/style><ul class=\"porto-info-list  porto-info-list81de0d7b252625259d0c0244a8c0a5bf wpb_custom_7601065cd5ca2b6d75d230f0c52ffa5a\"><li class=\"porto-info-list-item  wpb_custom_e140fdbed0f4dcf712ec01445fbb5e77\"><div class=\"porto-info-list-item-desc\"><span style=\"font-size: 24px;\">Security Services &#8211;\u00a0<\/span>Gestire la sicurezza dei tuoi dati: i Security Services di TaskBuilder Framework rappresentano il modo pi\u00f9 semplice e immediato per\u00a0tutelare i dati aziendali. Con i Security Services amministri la sicurezza\u00a0filtrando selettivamente\u00a0l&#8217;accesso a specifiche funzioni del prodotto,\u00a0profilando il livello di accesso\u00a0agli oggetti gestionali in Mago4 e impostando permessi e divieti di accesso a seconda di\u00a0ruoli\u00a0liberamente definiti.<\/p>\n<p>Con un\u2019interfaccia grafica intuitiva e flessibile, un\u2019impostazione dei\u00a0permessi\u00a0semplice, rapida e precisa e potenti risorse basate anche sulla\u00a0semantica, i Security Services di TaskBuilder Framework sono declinati secondo\u00a0due diversi livelli di protezione: Light e Standard, per una garanzia di sicurezza senza compromessi.<\/div><\/li><li class=\"porto-info-list-item  wpb_custom_da2a178d6e1cc619f1f9e1144c63f5fe\"><div class=\"porto-info-list-item-desc\"><span style=\"font-size: 24px;\">Auditing &#8211;<\/span> Monitorare l\u2019accesso ai dati ritenuti\u00a0pi\u00f9 sensibili: Auditing registra le operazioni eseguite sul database aziendale, consentendo un\u00a0monitoraggio\u00a0e una\u00a0tracciatura\u00a0continua dei dati e delle attivit\u00e0 degli utenti. Nell\u2019ambito del\u00a0controllo\u00a0e della\u00a0salvaguardia\u00a0delle informazioni aziendali, Auditing si integra con un\u00a0sistema di sicurezza potente ma non rigido, garantendo il livello di sicurezza che cerchi. I dati registrati\u00a0dal modulo\u00a0sono facilmente accessibili e sono possibili analisi\u00a0 avanzate.\u00a0Auditing \u00e8 pensato per la\u00a0massima usabilit\u00e0: \u00e8 semplice da configurare con poche operazioni, semplice da usare e da interrogare, grazie a strumenti specifici, query e report automatici.<\/div><\/li><li class=\"porto-info-list-item  wpb_custom_e140fdbed0f4dcf712ec01445fbb5e77\"><div class=\"porto-info-list-item-desc\"><span style=\"font-size: 24px;\">Magic Link <\/span>&#8211;\u00a0Con il server Magic Link puoi\u00a0interfacciarti a Mago4 tramite Web Services, qualsiasi sia il linguaggio di programmazione in uso.\u00a0Grazie a Magic Link, TaskBuilder Framework ha in s\u00e8 la capacit\u00e0 di mettere in comunicazione l&#8217;applicazione esterna con il tuo ERP.<\/div><\/li><li class=\"porto-info-list-item  wpb_custom_da2a178d6e1cc619f1f9e1144c63f5fe\"><div class=\"porto-info-list-item-desc\"><span style=\"font-size: 24px;\">DMS &#8211;<\/span> Con\u00a0DMS\u00a0(Document Management System)\u00a0gestisci gli allegati in forma elettronica\u00a0per qualsiasi documento gestionale. La gestione documentale di DMS ti consente di archiviare dati e documenti in forma elettronica per qualsiasi documento gestionale. DMS \u00e8 pensato per equipaggiarti con il sistema di riconoscimento\u00a0OCR\u00a0&#8211; utilizzato nella conversione immagine-testo, utile per la ricerca Full-Text Search e per la creazione di chiavi di ricerca a partire da porzioni del documento &#8211; e di\u00a0archiviazione massiva\u00a0dei documenti, con annessa funzionalit\u00e0 di\u00a0riconciliazione dei cartacei.\u00a0Cos\u00ec puoi protocollare i tuoi documenti e connetterti al servizio di Archiviazione Sostitutiva Zucchetti.<\/div><\/li><li class=\"porto-info-list-item  wpb_custom_e140fdbed0f4dcf712ec01445fbb5e77\"><div class=\"porto-info-list-item-desc\"><span style=\"font-size: 24px;\">Job Scheduler &#8211; <\/span>Con Job Scheduler programmi lo\u00a0svolgimento automatico di procedure all&#8217;interno o all&#8217;esterno del tuo gestionale, ad una data ed ora prefissata. Puoi anche definire sequenze articolate e composte di compiti secondo l\u2019ordine di esecuzione preferito.<\/div><\/li><\/ul>[\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1526302751352{padding: 25px !important;background-color: #f2f2f2 !important;}&#8221; el_class=&#8221;rounded&#8221;][vc_single_image image=&#8221;5418&#8243; img_size=&#8221;full&#8221;][vc_empty_space][vc_column_text]\n<h3>Tutti i plus del framework<\/h3>\n[\/vc_column_text]<div class=\"uavc-list-icon uavc-list-icon-wrapper ult-adjust-bottom-margin   \"><ul class=\"uavc-list\"><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-9931\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-9931 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><span style=\"font-size: 20px;\">Tool avanzati<\/span> Hai a disposizione tutti gli strumenti necessari alla creazione dei tuoi progetti di business.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-5955\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-5955 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><span style=\"font-size: 20px;\">Potente motore di Reportistica.<\/span> Interroghi facilmente la base dati della tua soluzione.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-9215\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-9215 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><span style=\"font-size: 20px;\">Alti livelli di sicurezza.<\/span> Proteggi e tracci i dati aziendali secondo profilazioni di diverso livello che incontrano le tue esigenze.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-9365\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-9365 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><span style=\"font-size: 20px;\">Gestione documentale efficace.<\/span>\u00a0Archivi l&#8217;esito dei tuoi flussi produttivi in un repository efficiente e facile da interrogare.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-3187\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-3187 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Interconnessione.Colleghi facilmente tra loro diversi componenti della tua soluzione tramite protocolli standard (XML e REST).<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-5353\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-5353 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Web Nativo.\u00a0Lavori dove e quando vuoi, su ogni dispositivo.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8462\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8462 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Tool avanzati. Hai a disposizione tutti gli strumenti necessari alla creazione dei tuoi progetti di business.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-9974\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-9974 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Espandibilit\u00e0<strong>.<\/strong>\u00a0Hai un solido supporto per far crescere la tua azienda implementando nuove funzionalit\u00e0.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-9827\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-9827 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Flessibilit\u00e0. Scegli la modalit\u00e0 di installazione che fa per te: Licenza su server aziendale, Cloud, PAAS.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-6251\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:10px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#22ccff;font-size:40px;display:inline-block;\">\n\t<i class=\"Simple-Line-Icons-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-6251 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Personalizzazione. Disponi di tutti gli strumenti per personalizzare ogni aspetto funzionale secondo le tue esigenze.<\/span><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; wrap_container=&#8221;yes&#8221; css=&#8221;.vc_custom_1565189849419{padding-top: 60px !important;padding-bottom: 40px !important;background-color: #ffffff !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner][vc_cta h2=&#8221;Quali sono i vantaggi di TB Framework?&#8221;]Che tu sia un utente o uno sviluppatore, TaskBuilder Framework \u00e8 la base applicativa da cui partire per realizzare i tuoi progetti. TaskBuilder Framework \u00e8 naturalmente predisposto alla collaborazione, alla gestione dei processi e alla reportistica, completando il quadro della suite Mago4 con componenti dedicate alla sicurezza e alla gestione documentale, da base ad avanzata, e molto altro.[\/vc_cta][\/vc_column_inner][\/vc_row_inner]<div class=\"wpb_custom_aa84c36a6a947f6099708744f0f74b68\"><div class=\"timeline-balloon p-b-lg m-b-sm   wpb_custom_e03dc5a8a169bfdfccbaed44883810c3\"><div class=\"balloon-cell balloon-time\"><span class=\"time-text step-item-subtitle\"><\/span><div class=\"time-dot background-color-light\"><\/div><\/div><div class=\"balloon-cell\"><div class=\"balloon-content background-color-light\"><span class=\"balloon-arrow\"><\/span><div class=\"balloon-description\"><div class=\"step-item-desc\"><span style=\"font-size: 24px;\">Sei un utente?<\/span><br \/>\nCon TaskBuilder Framework hai a disposizione un\u00a0insieme coerente di funzionalit\u00e0 applicative integrate, per incrementare il rendimento aziendale: dalla dematerializzazione documentale alla profilazione utenti, fino alla reportistica e alla tracciatura dati.<\/div><\/div><\/div><\/div><\/div><div class=\"timeline-balloon p-b-lg m-b-sm   wpb_custom_e03dc5a8a169bfdfccbaed44883810c3\"><div class=\"balloon-cell balloon-time\"><span class=\"time-text step-item-subtitle\"><\/span><div class=\"time-dot background-color-light\"><\/div><\/div><div class=\"balloon-cell\"><div class=\"balloon-content background-color-light\"><span class=\"balloon-arrow\"><\/span><div class=\"balloon-description\"><div class=\"step-item-desc\"><span style=\"font-size: 24px;\">Sei uno Sviluppatore? <\/span>Taskbuilder Framework ti offre l&#8217;impalcatura su cui operare per\u00a0creare nuove soluzioni\u00a0da proporre ai tuoi clienti. Con Taskbuilder Framework fondi e allo stesso temporendi operativi e coerenti i tuoi progetti, nel quadro di un&#8217;unica grande architettura.<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space][vc_column_text]\n<div id=\"ctl00_ctl00_MiddlePlaceHolder_PageMainContentHolder_TBSTecnologia1HtmlModule\">\n<h1>Tecnologia<\/h1>\n<p>TaskBuilder Framework si basa sulle solide fondamenta tecnologiche dell&#8217;ambiente di sviluppo TaskBuilder Studio (la diretta evoluzione del consolidato TaskBuilder.net). Questa\u00a0eredit\u00e0 tecnologica altamente specializzata\u00a0ha permesso di sviluppare\u00a0componenti performanti e robuste\u00a0grazie all&#8217;uso dei linguaggi di programmazione C++ e C#.<\/p>\n<p>Qualsiasi applicativo sviluppato con TaskBuilder Studio e ospitato da TaskBuilder Framework \u00e8 reso ancora pi\u00f9 completo da una sofisticata\u00a0gestione della tracciatura e del controllo di accessi e dati, grazie alle funzionalit\u00e0 Auditing e Security.<\/p>\n<p>Inoltre, ai fini dell\u2019integrazione con prodotti esterni, gli applicativi possono contare sull&#8217;infrastruttura di base che comprende il server MagicLink, per l\u2019accesso ed il\u00a0trasferimento bidirezionale di dati\u00a0con i Business Object, e la propriet\u00e0 di Single-Sign-On per una\u00a0gestione centralizzata dell\u2019autenticazione\u00a0utente.<\/p>\n<p>Non solo: con TaskBuilder Framework l\u2019utente ha a disposizione un semplice, ma efficace\u00a0sistema di archiviazione documentale, il DMS, e un\u00a0esecutore automatico di attivit\u00e0 funzionali ripetitive\u00a0chiamato Job Scheduler.<\/p>\n<p>TaskBuilder Framework fa uso del\u00a0framework Angular di Google\u00a0per la presentazione del menu delle funzioni applicative, soddisfando cos\u00ec la necessit\u00e0 di disporre di un\u2019interfaccia GDI o Web.<\/p>\n<p>TaskBuilder Framework ospita anche un\u00a0potente motore di reportistica, il Report Engine (esito dell&#8217;evoluzione del noto strumento Woorm), che conferisce ulteriore valore aggiunto all&#8217;applicativo: le interrogazioni sviluppate e rivolte alla base dati applicativa sapranno essere tanto sofisticate quanto esteticamente gradevoli grazie al modulo Reporting Studio di TaskBuilder Studio.<\/p>\n<p>Ultimo, ma non ultimo elemento di valore \u00e8 l\u2019interfaccia grafica: TaskBuilder Framework permette all\u2019utente di interagire con un\u00a0software dall\u2019aspetto gradevole\u00a0e dalla fruizione davvero\u00a0user-friendly\u00a0grazie a temi predefiniti e personalizzabili, sia nella modalit\u00e0 Desktop che in quella Web.<\/p><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; wrap_container=&#8221;yes&#8221; css=&#8221;.vc_custom_1525959313849{padding-top: 60px !important;padding-bottom: 40px !important;background-color: #f3f3f3 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_hoverbox 1=&#8221;&#8221; 2=&#8221;style=&#8220;&#8220;color:&#8221; 3=&#8221;#FFFFFF;&#8220;&gt;Highlights&#8221; 4=&#8221;tecnologici&#8221; 5=&#8221;&#8220;&#8221; image=&#8221;11826&#8243; primary_title=&#8221;Highlights tecnologici&#8221; primary_title_font_container=&#8221;color:%23ffffff&#8221; primary_title_google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; hover_title=&#8221;&#8221; el_width=&#8221;80&#8243; use_custom_fonts_primary_title=&#8221;true&#8221; primary_title_el_class=&#8221;testoBordato&#8221;]\n<ul>\n<li style=\"text-align: left;\">Client HTML5 + CSS3 + JavaScript<\/li>\n<li style=\"text-align: left;\">Back-End in C++\/C#<\/li>\n<li style=\"text-align: left;\">Risorse descritte in JSON dinamicamente<\/li>\n<li style=\"text-align: left;\">Eventi gestiti lato Client<\/li>\n<li style=\"text-align: left;\">Protocollo di comunicazione Ajax + WebSocket<\/li>\n<li style=\"text-align: left;\">Librerie client Javascript : AngularJS, JQuery<\/li>\n<\/ul>\n<p>&nbsp;[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1562836330780{margin-bottom: 30px !important;}&#8221; el_class=&#8221;bg-cover rounded&#8221;][vc_hoverbox 1=&#8221;&#8221; 2=&#8221;style=&#8220;&#8220;color:&#8221; 3=&#8221;#FFFFFF;&#8220;&gt;Requisiti&#8221; 4=&#8221;di&#8221; 5=&#8221;sistema&#8221; 6=&#8221;&#8220;&#8221; image=&#8221;11827&#8243; primary_title=&#8221;Requisiti di sistema&#8221; primary_title_font_container=&#8221;color:%23ffffff&#8221; primary_title_google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; hover_title=&#8221;&#8221; el_width=&#8221;80&#8243; use_custom_fonts_primary_title=&#8221;true&#8221; primary_title_el_class=&#8221;testoBordato&#8221;]\n<ul>\n<li style=\"text-align: left;\">Sistema operativo: Microsoft Windows 10, Windows 8, Windows 7, 2019, 2016, 2012, 2008 R2<\/li>\n<li style=\"text-align: left;\">CPU a 32 bit (X86) o 64 bit (X64)<\/li>\n<li style=\"text-align: left;\">RAM: seguire le specifiche indicate per il Sistema Operativo (consigliati 4 GB)<\/li>\n<li style=\"text-align: left;\">600MB di spazio disponibile su disco rigido<\/li>\n<li style=\"text-align: left;\">Risoluzione video consigliata: 1440&#215;900<\/li>\n<\/ul>\n<p>&nbsp;[\/vc_hoverbox][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; parallax=&#8221;content-moving&#8221; wrap_container=&#8221;yes&#8221; css=&#8221;.vc_custom_1526891136881{margin-bottom: 40px !important;padding-top: -100px !important;background-color: #ffffff !important;background-position: 0 0;background-repeat:-repeat;}&#8221; el_class=&#8221;bg-img-cover&#8221;][vc_column animation_type=&#8221;fadeIn&#8221;][rev_slider_vc alias=&#8221;it-_taskbuilderframework&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; wrap_container=&#8221;yes&#8221; text_align=&#8221;left&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; css=&#8221;.vc_custom_1525957325142{margin-top: 20px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 0px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 40px !important;padding-left: 0px !important;}&#8221; el_class=&#8221;bg-custom-color-1&#8243;][vc_column][vc_custom_heading text=&#8221;TaskBuilder Framework \u00e8 la base [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":11226,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-11426","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TaskBuilder Framework - Mago ERP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TaskBuilder Framework - Mago ERP\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; parallax=&#8221;content-moving&#8221; wrap_container=&#8221;yes&#8221; css=&#8221;.vc_custom_1526891136881{margin-bottom: 40px !important;padding-top: -100px !important;background-color: #ffffff !important;background-position: 0 0;background-repeat:-repeat;}&#8221; el_class=&#8221;bg-img-cover&#8221;][vc_column animation_type=&#8221;fadeIn&#8221;][rev_slider_vc alias=&#8221;it-_taskbuilderframework&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; wrap_container=&#8221;yes&#8221; text_align=&#8221;left&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; css=&#8221;.vc_custom_1525957325142{margin-top: 20px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 0px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 40px !important;padding-left: 0px !important;}&#8221; el_class=&#8221;bg-custom-color-1&#8243;][vc_column][vc_custom_heading text=&#8221;TaskBuilder Framework \u00e8 la base [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework\" \/>\n<meta property=\"og:site_name\" content=\"Mago ERP\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ZucchettiSoftware\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-04T14:34:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\\\/piattaforme-mago4\\\/framework\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\\\/piattaforme-mago4\\\/framework\",\"name\":\"TaskBuilder Framework - Mago ERP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#website\"},\"datePublished\":\"2019-07-31T13:55:00+00:00\",\"dateModified\":\"2021-02-04T14:34:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\\\/piattaforme-mago4\\\/framework#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\\\/piattaforme-mago4\\\/framework\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\\\/piattaforme-mago4\\\/framework#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mago-erp.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnologia &#038; Sviluppo\",\"item\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Overview delle piattaforme\",\"item\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/sviluppo\\\/piattaforme-mago4\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"TaskBuilder Framework\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#website\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/it\",\"name\":\"Mago ERP\",\"description\":\"Mago ERP\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mago-erp.com\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#organization\",\"name\":\"Zucchetti Group\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo.png\",\"width\":400,\"height\":98,\"caption\":\"Zucchetti Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/ZucchettiSoftware\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/zucchetti\",\"http:\\\/\\\/www.youtube.com\\\/mktzucche\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TaskBuilder Framework - Mago ERP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework","og_locale":"it_IT","og_type":"article","og_title":"TaskBuilder Framework - Mago ERP","og_description":"[vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; parallax=&#8221;content-moving&#8221; wrap_container=&#8221;yes&#8221; css=&#8221;.vc_custom_1526891136881{margin-bottom: 40px !important;padding-top: -100px !important;background-color: #ffffff !important;background-position: 0 0;background-repeat:-repeat;}&#8221; el_class=&#8221;bg-img-cover&#8221;][vc_column animation_type=&#8221;fadeIn&#8221;][rev_slider_vc alias=&#8221;it-_taskbuilderframework&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; wrap_container=&#8221;yes&#8221; text_align=&#8221;left&#8221; remove_margin_top=&#8221;yes&#8221; remove_margin_bottom=&#8221;yes&#8221; remove_border=&#8221;yes&#8221; css=&#8221;.vc_custom_1525957325142{margin-top: 20px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 0px !important;border-left-width: 0px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 40px !important;padding-left: 0px !important;}&#8221; el_class=&#8221;bg-custom-color-1&#8243;][vc_column][vc_custom_heading text=&#8221;TaskBuilder Framework \u00e8 la base [&hellip;]","og_url":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework","og_site_name":"Mago ERP","article_publisher":"http:\/\/www.facebook.com\/ZucchettiSoftware","article_modified_time":"2021-02-04T14:34:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework","url":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework","name":"TaskBuilder Framework - Mago ERP","isPartOf":{"@id":"https:\/\/www.mago-erp.com\/it#website"},"datePublished":"2019-07-31T13:55:00+00:00","dateModified":"2021-02-04T14:34:37+00:00","breadcrumb":{"@id":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4\/framework#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mago-erp.com\/it"},{"@type":"ListItem","position":2,"name":"Tecnologia &#038; Sviluppo","item":"https:\/\/www.mago-erp.com\/it\/sviluppo"},{"@type":"ListItem","position":3,"name":"Overview delle piattaforme","item":"https:\/\/www.mago-erp.com\/it\/sviluppo\/piattaforme-mago4"},{"@type":"ListItem","position":4,"name":"TaskBuilder Framework"}]},{"@type":"WebSite","@id":"https:\/\/www.mago-erp.com\/it#website","url":"https:\/\/www.mago-erp.com\/it","name":"Mago ERP","description":"Mago ERP","publisher":{"@id":"https:\/\/www.mago-erp.com\/it#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mago-erp.com\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mago-erp.com\/it#organization","name":"Zucchetti Group","url":"https:\/\/www.mago-erp.com\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mago-erp.com\/it#\/schema\/logo\/image\/","url":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2018\/04\/logo.png","contentUrl":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2018\/04\/logo.png","width":400,"height":98,"caption":"Zucchetti Group"},"image":{"@id":"https:\/\/www.mago-erp.com\/it#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ZucchettiSoftware","http:\/\/www.linkedin.com\/company\/zucchetti","http:\/\/www.youtube.com\/mktzucche"]}]}},"_links":{"self":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/pages\/11426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/comments?post=11426"}],"version-history":[{"count":0,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/pages\/11426\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/pages\/11226"}],"wp:attachment":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/media?parent=11426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}