{"id":9322,"date":"2019-03-29T11:43:55","date_gmt":"2019-03-29T10:43:55","guid":{"rendered":"https:\/\/www.mago-erp.com\/non-categorizzato\/express.html"},"modified":"2023-04-11T11:47:21","modified_gmt":"2023-04-11T09:47:21","slug":"express","status":"publish","type":"post","link":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html","title":{"rendered":"EXPRESS"},"content":{"rendered":"<p>Express \u00e8 l\u2019applicazione che consente una gestione semplice e immediata delle attivit\u00e0 quotidiane degli autotrasportatori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestione trasportatori semplice e completa<\/p>\n","protected":false},"author":12,"featured_media":9895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"single\/single-cat-vertical_solution.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[283],"tags":[],"markets_tag":[324],"business_needs_tag":[],"class_list":["post-9322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soluzioni-verticali","markets_tag-trasporti-e-magazzinaggio"],"acf":[],"featured_image_src":{"landsacpe":["https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png",154,66,false],"list":["https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png",154,66,false],"medium":["https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png",154,66,false],"full":["https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png",154,66,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXPRESS<\/title>\n<meta name=\"description\" content=\"Gestione trasportatori semplice e completa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXPRESS\" \/>\n<meta property=\"og:description\" content=\"Gestione trasportatori semplice e completa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html\" \/>\n<meta property=\"og:site_name\" content=\"Mago ERP\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ZucchettiSoftware\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-29T10:43:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T09:47:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png\" \/>\n\t<meta property=\"og:image:width\" content=\"154\" \/>\n\t<meta property=\"og:image:height\" content=\"66\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Riccardo Bondioli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Riccardo Bondioli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html\"},\"author\":{\"name\":\"Riccardo Bondioli\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#\\\/schema\\\/person\\\/5d4fcf3d7cd0a91c4752ab643cc47e5f\"},\"headline\":\"EXPRESS\",\"datePublished\":\"2019-03-29T10:43:55+00:00\",\"dateModified\":\"2023-04-11T09:47:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html\"},\"wordCount\":16,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LogoSolution1322.png\",\"articleSection\":[\"Soluzioni Verticali\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html\",\"name\":\"EXPRESS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LogoSolution1322.png\",\"datePublished\":\"2019-03-29T10:43:55+00:00\",\"dateModified\":\"2023-04-11T09:47:21+00:00\",\"description\":\"Gestione trasportatori semplice e completa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#primaryimage\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LogoSolution1322.png\",\"contentUrl\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LogoSolution1322.png\",\"width\":154,\"height\":66,\"caption\":\"EXPRESS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it\\\/soluzioni-verticali\\\/express.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mago-erp.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXPRESS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#website\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/it\",\"name\":\"Mago ERP\",\"description\":\"Mago ERP\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mago-erp.com\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#organization\",\"name\":\"Zucchetti Group\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.mago-erp.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/logo.png\",\"width\":400,\"height\":98,\"caption\":\"Zucchetti Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/ZucchettiSoftware\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/zucchetti\",\"http:\\\/\\\/www.youtube.com\\\/mktzucche\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mago-erp.com\\\/it#\\\/schema\\\/person\\\/5d4fcf3d7cd0a91c4752ab643cc47e5f\",\"name\":\"Riccardo Bondioli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ca4cace50a7a767cda29366927de4d8a02f5b5a96942c8102dc7cd50bbe76a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ca4cace50a7a767cda29366927de4d8a02f5b5a96942c8102dc7cd50bbe76a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ca4cace50a7a767cda29366927de4d8a02f5b5a96942c8102dc7cd50bbe76a?s=96&d=mm&r=g\",\"caption\":\"Riccardo Bondioli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXPRESS","description":"Gestione trasportatori semplice e completa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html","og_locale":"it_IT","og_type":"article","og_title":"EXPRESS","og_description":"Gestione trasportatori semplice e completa","og_url":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html","og_site_name":"Mago ERP","article_publisher":"http:\/\/www.facebook.com\/ZucchettiSoftware","article_published_time":"2019-03-29T10:43:55+00:00","article_modified_time":"2023-04-11T09:47:21+00:00","og_image":[{"width":154,"height":66,"url":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png","type":"image\/png"}],"author":"Riccardo Bondioli","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Riccardo Bondioli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#article","isPartOf":{"@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html"},"author":{"name":"Riccardo Bondioli","@id":"https:\/\/www.mago-erp.com\/it#\/schema\/person\/5d4fcf3d7cd0a91c4752ab643cc47e5f"},"headline":"EXPRESS","datePublished":"2019-03-29T10:43:55+00:00","dateModified":"2023-04-11T09:47:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html"},"wordCount":16,"publisher":{"@id":"https:\/\/www.mago-erp.com\/it#organization"},"image":{"@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#primaryimage"},"thumbnailUrl":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png","articleSection":["Soluzioni Verticali"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html","url":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html","name":"EXPRESS","isPartOf":{"@id":"https:\/\/www.mago-erp.com\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#primaryimage"},"image":{"@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#primaryimage"},"thumbnailUrl":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png","datePublished":"2019-03-29T10:43:55+00:00","dateModified":"2023-04-11T09:47:21+00:00","description":"Gestione trasportatori semplice e completa","breadcrumb":{"@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#primaryimage","url":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png","contentUrl":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2019\/03\/LogoSolution1322.png","width":154,"height":66,"caption":"EXPRESS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mago-erp.com\/it\/soluzioni-verticali\/express.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mago-erp.com\/it"},{"@type":"ListItem","position":2,"name":"EXPRESS"}]},{"@type":"WebSite","@id":"https:\/\/www.mago-erp.com\/it#website","url":"https:\/\/www.mago-erp.com\/it","name":"Mago ERP","description":"Mago ERP","publisher":{"@id":"https:\/\/www.mago-erp.com\/it#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mago-erp.com\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mago-erp.com\/it#organization","name":"Zucchetti Group","url":"https:\/\/www.mago-erp.com\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mago-erp.com\/it#\/schema\/logo\/image\/","url":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2018\/04\/logo.png","contentUrl":"https:\/\/www.mago-erp.com\/wp-content\/uploads\/2018\/04\/logo.png","width":400,"height":98,"caption":"Zucchetti Group"},"image":{"@id":"https:\/\/www.mago-erp.com\/it#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ZucchettiSoftware","http:\/\/www.linkedin.com\/company\/zucchetti","http:\/\/www.youtube.com\/mktzucche"]},{"@type":"Person","@id":"https:\/\/www.mago-erp.com\/it#\/schema\/person\/5d4fcf3d7cd0a91c4752ab643cc47e5f","name":"Riccardo Bondioli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/83ca4cace50a7a767cda29366927de4d8a02f5b5a96942c8102dc7cd50bbe76a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ca4cace50a7a767cda29366927de4d8a02f5b5a96942c8102dc7cd50bbe76a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ca4cace50a7a767cda29366927de4d8a02f5b5a96942c8102dc7cd50bbe76a?s=96&d=mm&r=g","caption":"Riccardo Bondioli"}}]}},"_links":{"self":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/posts\/9322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/comments?post=9322"}],"version-history":[{"count":1,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/posts\/9322\/revisions"}],"predecessor-version":[{"id":19553,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/posts\/9322\/revisions\/19553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/media\/9895"}],"wp:attachment":[{"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/media?parent=9322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/categories?post=9322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/tags?post=9322"},{"taxonomy":"markets_tag","embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/markets_tag?post=9322"},{"taxonomy":"business_needs_tag","embeddable":true,"href":"https:\/\/www.mago-erp.com\/it\/wp-json\/wp\/v2\/business_needs_tag?post=9322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}